{"id":16163,"date":"2025-06-04T14:50:10","date_gmt":"2025-06-04T12:50:10","guid":{"rendered":"https:\/\/stage.ligula.se\/hosting\/best-western-plus-park-city-solna\/"},"modified":"2025-12-29T14:40:05","modified_gmt":"2025-12-29T13:40:05","slug":"best-western-plus-park-city-solna","status":"publish","type":"page","link":"https:\/\/ligula.se\/en\/hosting\/best-western-plus-park-city-solna\/","title":{"rendered":"Best Western Plus Park City Solna"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":5893,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-hotels.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-16163","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:22:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/pages\/16163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/comments?post=16163"}],"version-history":[{"count":0,"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/pages\/16163\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/pages\/5893"}],"wp:attachment":[{"href":"https:\/\/ligula.se\/en\/wp-json\/wp\/v2\/media?parent=16163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}